{"id":8189,"date":"2017-08-05T11:56:27","date_gmt":"2017-08-05T09:56:27","guid":{"rendered":"http:\/\/www.sportcinofili.it\/?p=8189"},"modified":"2017-08-05T11:58:21","modified_gmt":"2017-08-05T09:58:21","slug":"comunicato-stampa-finale-di-selezione-ifcs-raduni-della-nazionale2018","status":"publish","type":"post","link":"https:\/\/www.sportcinofili.it\/index.php\/news\/comunicato-stampa-finale-di-selezione-ifcs-raduni-della-nazionale2018\/","title":{"rendered":"COMUNICATO STAMPA: Finale di selezione IFCS &#038; raduni della Nazionale2018"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><img decoding=\"async\" class=\"size-thumbnail wp-image-8191 alignleft\" src=\"http:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/08\/LOGO_WAC2018_ver3500500-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/08\/LOGO_WAC2018_ver3500500-150x150.jpg 150w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/08\/LOGO_WAC2018_ver3500500-300x300.jpg 300w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/08\/LOGO_WAC2018_ver3500500-230x230.jpg 230w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/08\/LOGO_WAC2018_ver3500500-350x351.jpg 350w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/08\/LOGO_WAC2018_ver3500500-480x481.jpg 480w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/08\/LOGO_WAC2018_ver3500500.jpg 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>Sabato 25 novembre<\/strong> si svolger\u00e0 presso il <strong>Circolo Ippico di Castellazzo<\/strong> (Bollate \u2013 MI) la <strong>finale di selezione della Nazionale IFCS2018<\/strong> che parteciper\u00e0 al <strong>World Agility Championship IFCS 2018<\/strong> in Italia. Alla finale avranno accesso i migliori binomi senior che avranno accumulato punti durante le gare del Campionato Nazionale FISC-MASTER-METICCI 2017. I punti del campionato sono consultabili a <a href=\"http:\/\/www.agilitymaster.com\/am\/index.php?punteggi-2017\">questo link\u00a0<\/a><\/p>\n<p style=\"text-align: justify;\">Al termine del campionato saranno pubblicate sul sito <a href=\"http:\/\/www.sportcinofili.it\">www.sportcinofili.it<\/a> le liste dei binomi che avranno accesso alla Finale di Selezione della Nazionale. La finale sar\u00e0 giudicata da Fabiano Gatto, nonch\u00e9 giudice italiano al WAC2018. La finale si svolger\u00e0 in 4 altezze secondo il regolamento previsto dall\u2019IFCS.<\/p>\n<p style=\"text-align: justify;\">Al termine della Finale di selezione e della finale di Campionato FISC-Master-Meticci saranno comunicati i nominativi della nazionale. La nazionale sar\u00e0 composta da <strong>16 binomi<\/strong> + <strong>4 binomi<\/strong> che hanno ottenuto una medaglia nelle precedenti edizioni del WAC. I 16 binomi saranno cos\u00ec composti: 4 binomi vincitori della finale di selezione del sabato (super combinata), 3 binomi vincitori della finale Master (combinata agility-jumping), 3 binomi vincitori della finale di campionato meticci (combinata agility-jumping) e sei binomi scelti dal selezionatore tra i presenti alla finale.<\/p>\n<p style=\"text-align: justify;\">Sono state definite le date dei raduni della nazionale IFCS2018:<\/p>\n<ul style=\"text-align: justify;\">\n<li>1\u00b0 raduno \u2013 13 e 14 gennaio 2018<\/li>\n<li>2\u00b0 raduno &#8211; 3 e 4 febbraio 2018<\/li>\n<li>3\u00b0 raduno &#8211; 3 e 4 marzo 2018<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">L&#8217;arrivo ai raduni \u00e8 previsto per il sabato mattina e le attivit\u00e0 si svilupperanno cos\u00ec come segue:<\/p>\n<p style=\"text-align: justify;\">&#8211; <strong><u>1\u00b0 raduno<\/u><\/strong> ci sar\u00e0 la presentazione del programma di preparazione atletica del conduttore a cura di <strong>Roberto Farioli<\/strong> e del cane a cura di <strong>Francesca Bussi<\/strong>. Il Team Coach <strong>Alfonso Sabbatini<\/strong> curer\u00e0 la preparazione del <strong>biathlon <\/strong>con la dovuta spiegazione del regolamento del mondiale.<\/p>\n<p style=\"text-align: justify;\">&#8211; <strong><u>2\u00b0 raduno<\/u><\/strong> si svolger\u00e0 la preparazione atletica del conduttore e del cane come sopra. Il Team Coach curer\u00e0 la presentazione dei giochi <strong>gamblers<\/strong> e <strong>snooker<\/strong> (Regolamento IFCS e prova pratica).<\/p>\n<p style=\"text-align: justify;\">&#8211; <strong><u>3\u00b0 raduno<\/u><\/strong> si svolger\u00e0 la preparazione atletica del conduttore e del cane come sopra. Il Team Coach curer\u00e0 la spiegazione del <strong>triathlon<\/strong> e la preparazione della staffetta.<\/p>\n<p style=\"text-align: justify;\">Alla sera del sabato si cener\u00e0 tutti insieme, l\u2019obiettivo \u00e8 quello di creare coesione e gruppo all&#8217;interno dei membri della nazionale. I lavori riprenderanno la domenica fino al primo pomeriggio.\u00a0 I raduni saranno ospitati a Cardano al Campo (VA) presso il campo coperto. La Federazione comunicher\u00e0 a tutti i membri della nazionale le strutture convenzionate per alloggiare durante i raduni.<\/p>\n<p style=\"text-align: justify;\"><strong>Sabato 25 novembre<\/strong>, prima dell\u2019inizio della finale, il selezionatore e Team Coach incontrer\u00e0 tutti i binomi Senior con l\u2019obiettivo di presentare dettagliatamente il programma dei raduni e delle attivit\u00e0 prima della chiamata della Nazionale. Tutti i binomi selezionati per far parte della nazionale dovranno necessariamente partecipare a tutte le attivit\u00e0 di preparazione al mondiale previste dal Team Coach come precedentemente specificato.<\/p>\n<p style=\"text-align: right;\">Il Selezionatore e Team Coach <strong>Alfonso Sabbatini<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 25 novembre si svolger\u00e0 presso il Circolo Ippico di Castellazzo (Bollate \u2013 MI) la finale di selezione della Nazionale IFCS2018 che parteciper\u00e0 al World Agility Championship IFCS 2018 in Italia. Alla finale avranno accesso i migliori binomi senior che avranno accumulato punti durante le gare del Campionato Nazionale FISC-MASTER-METICCI [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8193,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts\/8189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/comments?post=8189"}],"version-history":[{"count":1,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts\/8189\/revisions"}],"predecessor-version":[{"id":8192,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts\/8189\/revisions\/8192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/media\/8193"}],"wp:attachment":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/media?parent=8189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/categories?post=8189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/tags?post=8189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}