{"id":3862,"date":"2015-05-22T11:00:07","date_gmt":"2015-05-22T09:00:07","guid":{"rendered":"http:\/\/www.sporttennis.it\/sportcinofili\/?p=3862"},"modified":"2016-10-20T14:49:27","modified_gmt":"2016-10-20T12:49:27","slug":"le-sfumature-di-grigio","status":"publish","type":"post","link":"https:\/\/www.sportcinofili.it\/index.php\/news\/le-sfumature-di-grigio\/","title":{"rendered":"Le sfumature di grigio"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-3863 alignleft\" src=\"http:\/\/www.sportcinofili.it\/wp-content\/uploads\/2016\/09\/grey-300x200.jpg\" alt=\"grey\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2016\/09\/grey-300x200.jpg 300w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2016\/09\/grey-230x153.jpg 230w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2016\/09\/grey-350x233.jpg 350w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2016\/09\/grey-480x320.jpg 480w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2016\/09\/grey.jpg 736w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Nel vasto panorama delle razze canine il colore grigio \u00e8 direttamente poco diffuso e, dal punto di vista genetico, sono diversi i geni chiamati in causa. Nel lupo e nei canidi selvatici l\u2019eumelanina e la feomelanina sono entrambe presenti, mescolati in una combinazione di peli chiari, scuri e con vari concentrazioni di \u201cagouti\u201d o grigio lupo che \u00e8 scomparso in quasi tutti i cani domestici, fatta eccezione per alcune razze come i nordici, alcuni spitz, i cani lupo e il Pastore Tedesco grigio molto apprezzato come cane da lavoro.<\/p>\n<p style=\"text-align: justify;\">In altre razze, invece, \u00e8 presente l\u2019allele dominante della serie G il gene che determina una tinta progressivamente sempre pi\u00f9 grigia nei mantelli di cani che nascono neri e che tendono poi ad assumere sfumature blu o grigio-blu; nella forma \u201cG\u201d determina un progressivo ingrigimento del mantello, nella forma \u201cg\u201d non si verifica alcun ingrigimento del mantello.<\/p>\n<p style=\"text-align: justify;\">Si possono ottenere tre forme genetiche: GG, gG e gg. Nella prima e nella seconda si manifestano sfumature blu, mentre i \u201cgg\u201d rimangono neri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel vasto panorama delle razze canine il colore grigio \u00e8 direttamente poco diffuso e, dal punto di vista genetico, sono diversi i geni chiamati in causa. Nel lupo e nei canidi selvatici l\u2019eumelanina e la feomelanina sono entrambe presenti, mescolati in una combinazione di peli chiari, scuri e con vari [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3862","post","type-post","status-publish","format-standard","hentry","category-news"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts\/3862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/comments?post=3862"}],"version-history":[{"count":2,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts\/3862\/revisions"}],"predecessor-version":[{"id":5481,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts\/3862\/revisions\/5481"}],"wp:attachment":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/media?parent=3862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/categories?post=3862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/tags?post=3862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}