{"id":18191,"date":"2020-10-27T09:00:33","date_gmt":"2020-10-27T08:00:33","guid":{"rendered":"http:\/\/www.sportcinofili.it\/?p=18191"},"modified":"2020-10-27T10:36:29","modified_gmt":"2020-10-27T09:36:29","slug":"esami-del-corso-istruttori-di-rally-obedience-di-2-livello","status":"publish","type":"post","link":"https:\/\/www.sportcinofili.it\/index.php\/news\/esami-del-corso-istruttori-di-rally-obedience-di-2-livello\/","title":{"rendered":"Esami del corso istruttori di rally-obedience di 2\u00b0 livello"},"content":{"rendered":"\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/www.sportcinofili.it\/wp-content\/uploads\/2020\/10\/Esame-istruttori-2\u00b0-livello-camponogara-1024x768.jpeg\" alt=\"\" data-id=\"18192\" data-full-url=\"http:\/\/www.sportcinofili.it\/wp-content\/uploads\/2020\/10\/Esame-istruttori-2\u00b0-livello-camponogara.jpeg\" data-link=\"http:\/\/www.sportcinofili.it\/?attachment_id=18192\" class=\"wp-image-18192\" srcset=\"https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2020\/10\/Esame-istruttori-2\u00b0-livello-camponogara-1024x768.jpeg 1024w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2020\/10\/Esame-istruttori-2\u00b0-livello-camponogara-300x225.jpeg 300w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2020\/10\/Esame-istruttori-2\u00b0-livello-camponogara-768x576.jpeg 768w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2020\/10\/Esame-istruttori-2\u00b0-livello-camponogara-1536x1152.jpeg 1536w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2020\/10\/Esame-istruttori-2\u00b0-livello-camponogara-830x623.jpeg 830w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2020\/10\/Esame-istruttori-2\u00b0-livello-camponogara-230x173.jpeg 230w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2020\/10\/Esame-istruttori-2\u00b0-livello-camponogara-350x263.jpeg 350w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2020\/10\/Esame-istruttori-2\u00b0-livello-camponogara-480x360.jpeg 480w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2020\/10\/Esame-istruttori-2\u00b0-livello-camponogara.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Mercoled\u00ec 14 e domenica 18 ottobre si sono svolti rispettivamente a Genzano di Roma, presso Il Cane a Norma, e a Camponogara, presso la Casa di Molly, gli esami del corso istruttori di rally-obedience di 2\u00b0 livello, svoltosi\u00a0sotto la docenza di Marco Chiaro.Il corso ha visto svolgersi la parte di teoria in modalit\u00e0 online, raggruppando insieme i due gruppi di candidati, e la parte pratica e l&#8217;esame in campo.Questa modalit\u00e0 si sta rivelando vincente, funzionale e produttiva. Gli incontri in diretta, dalla durata di 2 ore, consentono una concentrazione intensa e quindi un apprendimento migliore\u00a0 pi\u00f9 approfondito. Il tempo che\u00a0intercorre fra una lezione e l&#8217;altra permette di elaborare al meglio le informazioni e di chiarire i dubbi nella lezione successiva.La conclusione in campo completa il percorso.L&#8217;istruttore di rally-obedience di 2\u00b0 livello \u00e8 il tecnico che, acquisite le competenze per la preparazione\u00a0dei binomi su tutti e 3 il livelli (L1, L2 e L3), \u00e8 abilitato a essere indicato come tecnico dei Centri Cinofili che intendono partecipare al Campionato Italiano e a quello Interregionale per Club.Complimenti ai neo istruttori di 2\u00b0 livello Flavia Bordi, Ilaria Marra, Roberta Lentini, Laura Pelletti, Chiara Diosono, Maria Garbo, Annalisa Perissinotto, Davide Ongarato, Marco Trov\u00f2, Clelia Valdini, Giulia Dal Sasso, Andrea Marciani e Mario Gianformaggio.Grazie ai presidenti di Commissione di esame Paola Catalano e Caterina Russo.Un ringraziamento particolare al Cane a Norma e alla Casa di Molly per la consueta calorosa ospitalit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercoled\u00ec 14 e domenica 18 ottobre si sono svolti rispettivamente a Genzano di Roma, presso Il Cane a Norma, e a Camponogara, presso la Casa di Molly, gli esami del corso istruttori di rally-obedience di 2\u00b0 livello, svoltosi\u00a0sotto la docenza di Marco Chiaro.Il corso ha visto svolgersi la parte di [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts\/18191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/comments?post=18191"}],"version-history":[{"count":2,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts\/18191\/revisions"}],"predecessor-version":[{"id":18197,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts\/18191\/revisions\/18197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/media\/18192"}],"wp:attachment":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/media?parent=18191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/categories?post=18191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/tags?post=18191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}