{"id":18186,"date":"2020-10-26T11:42:35","date_gmt":"2020-10-26T10:42:35","guid":{"rendered":"http:\/\/www.sportcinofili.it\/?p=18186"},"modified":"2020-10-26T14:02:35","modified_gmt":"2020-10-26T13:02:35","slug":"aggiornamento-dpcm-24-ottobre-2020","status":"publish","type":"post","link":"https:\/\/www.sportcinofili.it\/index.php\/news\/aggiornamento-dpcm-24-ottobre-2020\/","title":{"rendered":"Aggiornamento DPCM 24 ottobre 2020"},"content":{"rendered":"\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"http:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/12\/importante-avviaso-300x300.png\" alt=\"\" data-id=\"9673\" data-full-url=\"http:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/12\/importante-avviaso-300x300.png\" data-link=\"http:\/\/www.sportcinofili.it\/index.php\/news\/nuovo-regolamento-2018-guida-ad-ospitare-i-corsi-2\/attachment\/importante-avviaso-300x300\/\" class=\"wp-image-9673\" srcset=\"https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/12\/importante-avviaso-300x300.png 600w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/12\/importante-avviaso-300x300-150x150.png 150w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/12\/importante-avviaso-300x300-300x300.png 300w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/12\/importante-avviaso-300x300-148x148.png 148w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/12\/importante-avviaso-300x300-31x31.png 31w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/12\/importante-avviaso-300x300-38x38.png 38w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/12\/importante-avviaso-300x300-215x215.png 215w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/12\/importante-avviaso-300x300-230x230.png 230w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/12\/importante-avviaso-300x300-350x350.png 350w, https:\/\/www.sportcinofili.it\/wp-content\/uploads\/2017\/12\/importante-avviaso-300x300-480x480.png 480w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Il Presidente del Consiglio, Giuseppe Conte, ha firmato il nuovo DPCM sulle misure per il contrasto e il contenimento dell&#8217;emergenza Covid-19. Per quanto riguarda lo sport \u00e8 confermata la possibilit\u00e0 di &#8220;svolgere attivit\u00e0 sportiva o attivit\u00e0 motoria all&#8217;aperto&#8221;.<\/p>\n\n\n\n<p>L\u2019attivit\u00e0 sportiva cinotecnica non \u00e8 inserita negli sport di contatto, quindi si pu\u00f2 svolgere a condizione che si rispettino i \u201cprotocolli di sicurezza\u201d stabiliti dell\u2019Organismo del CONI, a cui si \u00e8 affiliato. Inoltre, se si svolgono \u201ceventi didattici\u201d (si intendono lezioni, allenamenti della durata di almeno un mese e con frequenza minima di 1 volta a settimana), i predetti eventi dovranno essere comunicati con largo anticipo alla nostra segreteria con l\u2019indicazione delle date ed istruttore ed alla fine dell\u2019evento si dovr\u00e0 comunicare l\u2019elenco dei partecipanti (obbligatoriamente tesserati, entro 10 gg.).<\/p>\n\n\n\n<p>Possono essere svolte le seguenti attivit\u00e0:<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Gli eventi e le competizioni sportive, riconosciuti di interesse nazionale, nei settori professionistici e dilettantistici, dal Comitato Olimpico Nazionale Italiano (CONI), dal Comitato Italiano Paralimpico (CIP), dalle rispettive Federazioni Sportive Nazionali, Enti di Promozione Sportiva, ovvero (\u2026) organizzati all\u2019interno di impianti sportivi utilizzati a porte chiuse, ovvero all\u2019aperto senza presenza del pubblico e nel rispetto dei \u201cprotocolli di sicurezza\u201d (distanziamento sociale, utilizzo delle mascherine, utilizzo di gel\u2026) , gi\u00e0 resi noti in precedenti articoli.<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;lezioni ed allenamenti individuali si possono effettuare. Se le predette lezioni di attivit\u00e0 sportive cinotecniche sono ripetitive nel mese, va comunicato alla segreteria lo svolgimento di un \u201cevento didattico\u201d con le modalit\u00e0 sopra indicate;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;La formazione \u00e8 consentita solo online;<\/p>\n\n\n\n<p>Le predette agevolazioni riguardano esclusivamente le asd e ssd affiliate ad un Organismo CONI, sono escluse dalle predette agevolazioni, inerenti le attivit\u00e0 sportive, le ass. di promozione sociale, ditte individuali, ecc\u2026<\/p>\n\n\n\n<p>In ogni caso per ulteriori chiarimenti e delucidazioni fa fede il DPCM consultabile al seguente link e si ricorda che ogni Regione o Comune potrebbe emanare un&#8217;Ordinanza pi\u00f9 restrittiva del DPCM, quindi in questi casi \u00e8 opportuno contattare il proprio Comune di competenza:<\/p>\n\n\n\n<p><strong><a href=\"http:\/\/www.governo.it\/sites\/new.governo.it\/files\/DPCM_20201024.pdf\">CLICCA QUI<\/a><\/strong>&nbsp;per vedere il testo completo del DPCM<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/drive.google.com\/file\/d\/1HeKn0wF3WYuKNoq1ANFqJ3qtHKCapoLa\/view?usp=sharing\">CLICCA QUI<\/a> <\/strong>per scaricare il protocollo gare<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/drive.google.com\/file\/d\/1Fv3Gzif6A8J_izTJHXy4HvbR7WZyFnyW\/view\">CLICCA QUI<\/a><\/strong> Per scaricare la modulistica attestante le condizioni di salute<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Presidente del Consiglio, Giuseppe Conte, ha firmato il nuovo DPCM sulle misure per il contrasto e il contenimento dell&#8217;emergenza Covid-19. Per quanto riguarda lo sport \u00e8 confermata la possibilit\u00e0 di &#8220;svolgere attivit\u00e0 sportiva o attivit\u00e0 motoria all&#8217;aperto&#8221;. L\u2019attivit\u00e0 sportiva cinotecnica non \u00e8 inserita negli sport di contatto, quindi si [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts\/18186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/comments?post=18186"}],"version-history":[{"count":2,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts\/18186\/revisions"}],"predecessor-version":[{"id":18194,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/posts\/18186\/revisions\/18194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/media\/18192"}],"wp:attachment":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/media?parent=18186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/categories?post=18186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/tags?post=18186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}