{"id":6106,"date":"2016-12-21T10:31:41","date_gmt":"2016-12-21T09:31:41","guid":{"rendered":"http:\/\/www.sportcinofili.it\/?page_id=6106"},"modified":"2025-02-20T15:05:20","modified_gmt":"2025-02-20T14:05:20","slug":"come-diventare-istruttore-di-agility","status":"publish","type":"page","link":"https:\/\/www.sportcinofili.it\/index.php\/come-diventare-istruttore-di-agility\/","title":{"rendered":"Come diventare Istruttore di Agility"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6106\" class=\"elementor elementor-6106\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42e67c68 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42e67c68\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c683f7c\" data-id=\"6c683f7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-379d054c elementor-widget elementor-widget-text-editor\" data-id=\"379d054c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La\u00a0 Federazione\u00a0 Italiana\u00a0 Sporti\u00a0 Cinofili\u00a0 favorisce\u00a0 e promuove\u00a0 la\u00a0 diffusione\u00a0 di\u00a0 tutte\u00a0 le discipline\u00a0 sportive\u00a0 cinofile,\u00a0 nel\u00a0 particolare\u00a0 la\u00a0 formazione\u00a0 degli\u00a0 Istruttori\u00a0 di\u00a0 Agility\u00a0 Dog.\u00a0 Lo scopo\u00a0 del\u00a0 corso\u00a0 \u00e8\u00a0 di\u00a0 dare\u00a0 ai\u00a0 candidati\u00a0 una\u00a0 tecnica in\u00a0 tema\u00a0 di\u00a0 istruzione\u00a0 cinofila\u00a0 perl\u2019insegnamento ed il conseguimento del brevetto di Istruttore di Agility Dog. La struttura del corso di formazione prevede il seguente iter formativo:<\/p><ul><li>ISTRUTTORE DI AGILITY PRIMO LIVELLO: (54 ore)<\/li><li>ISTRUTTORE DI AGILITY SECONDO LIVELLO:\u00a0 (54 ore)<\/li><li>ISTRUTTORE DI AGILITY TERZO LIVELLO (54 ore)<\/li><li>TECNICO FORMATORE DI ISTRUTTORI DI AGILITY<\/li><\/ul><p><a href=\"http:\/\/www.sportcinofili.it\/index.php\/download-documenti\/regolamenti-di-settore\/regolamenti-agility-dog\/\">CLICCA QUI<\/a> per andare alla pagina dei Regolamenti di Agility Dog<\/p><hr \/><p>I corsi di formazione sono suddivisi in livelli, ciascun livello prevede 54 ore di lezione teorico\/pratico e un esame finale. Sono previsti anche corsi di 3\u00b0 livello a ciclo unico (162 ore) che comprendono degli esami intermedi di 1\u00b0 e 2\u00b0 livello.<\/p><h5><span style=\"text-decoration: underline;\">Corsi in programma:<\/span><\/h5><ul><li>Dal 23 Settembre 2024 &#8211; <span style=\"text-decoration: underline;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1RZ9nJrLA2BcsrImx4EvYDxcphba0sdHX\/view?usp=sharing\"><strong>CORSO ISTRUTTORE 1\u00b0 LIVELLO AGILITY<\/strong><\/a><\/span> &#8211; Ciclo Unico &#8211; <strong>San Miniato (Pisa)<\/strong>&#8211; LED STAR AGILITY TEAM<\/li><\/ul><h5 style=\"text-align: left;\"><strong><span style=\"text-decoration: underline;\">Corsi svolti:<\/span><br \/><\/strong><\/h5><ul><li>in aggiornamento<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La\u00a0 Federazione\u00a0 Italiana\u00a0 Sporti\u00a0 Cinofili\u00a0 favorisce\u00a0 e promuove\u00a0 la\u00a0 diffusione\u00a0 di\u00a0 tutte\u00a0 le discipline\u00a0 sportive\u00a0 cinofile,\u00a0 nel\u00a0 particolare\u00a0 la\u00a0 formazione\u00a0 degli\u00a0 Istruttori\u00a0 di\u00a0 Agility\u00a0 Dog.\u00a0 Lo scopo\u00a0 del\u00a0 corso\u00a0 \u00e8\u00a0 di\u00a0 dare\u00a0 ai\u00a0 candidati\u00a0 una\u00a0 tecnica in\u00a0 tema\u00a0 di\u00a0 istruzione\u00a0 cinofila\u00a0 perl\u2019insegnamento ed il conseguimento del brevetto di Istruttore di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-6106","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/pages\/6106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/comments?post=6106"}],"version-history":[{"count":27,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/pages\/6106\/revisions"}],"predecessor-version":[{"id":32713,"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/pages\/6106\/revisions\/32713"}],"wp:attachment":[{"href":"https:\/\/www.sportcinofili.it\/index.php\/wp-json\/wp\/v2\/media?parent=6106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}